                                        
                                        
                                        
                                        
                                        
                                        
                                        
                                        
                                        
                                        
                                        
                                        
                                        
                                        
                                        
                                        
                                        
                                        
{"id":9497,"date":"2026-02-07T18:37:03","date_gmt":"2026-02-07T17:37:03","guid":{"rendered":"https:\/\/oriamendi.eus\/?p=9497"},"modified":"2026-02-07T18:37:03","modified_gmt":"2026-02-07T17:37:03","slug":"ansa-ii-deja-en-ocho-tantos-a-juanenea","status":"publish","type":"post","link":"https:\/\/oriamendi.eus\/es\/2026\/02\/07\/ansa-ii-deja-en-ocho-tantos-a-juanenea\/","title":{"rendered":"Ansa II deja en ocho tantos a Juanenea"},"content":{"rendered":"<div>Ansa II ha comenzado de la mejor manera la liguilla del Torneo Masters Kutxabank despu\u00e9s de ganar 30-8 a Juanenea, actual campe\u00f3n del individual. Este marcador deja a Juanenea con menos un punto y Ansa suma cuatro puntos. Por lo tanto, el delantero de Urnieta tiene pie y medio en la final del campeonato.<\/div>\n<div>El partido no tuvo apenas historia. El marcador habla por s\u00ed solo. La superioridad de Ansa fue total desde el inicio hasta el final ante un desdibujado Juanenea. El de Urnieta hizo lo suyo, pero el de Saldias estuvo lejos de su nivel. Ansa hizo hasta quince tantos de saque y catorce en el peloteo por un error de Juanenea. El de Saldias hizo siete tantos en el peloteo y uno de saque.<\/div>\n<div>La diferencia entre uno y otro fue abismal. El ganador estuvo mejor en todas las facetas del juego. Una pena que no hubiera m\u00e1s emoci\u00f3n o m\u00e1s juego. El partido dur\u00f3 alrededor de 30 minutos sin apenas peloteo.<\/div>\n<div>El partido comenz\u00f3 ya con un parcial de 0-6 de salida que aument\u00f3 al 2-14, 3-22, y la m\u00e1xima lleg\u00f3 en el 8-30. Es duro decirlo pero hacia el final Juanenea maquill\u00f3 algo un marcador que pod\u00eda ser de esc\u00e1ndalo.<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Ansa II ha comenzado de la mejor manera la liguilla del Torneo Masters Kutxabank despu\u00e9s de ganar 30-8 a Juanenea, actual campe\u00f3n del individual. Este marcador deja a Juanenea con menos un punto y Ansa suma cuatro puntos. Por lo tanto, el delantero de Urnieta tiene pie y medio en la final del campeonato. El [&hellip;]<\/p>\n","protected":false},"author":5,"featured_media":9496,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_et_pb_use_builder":"","_et_pb_old_content":"","_et_gb_content_width":"","footnotes":""},"categories":[1],"tags":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v21.8 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Ansa II deja en ocho tantos a Juanenea | Oriamendi 2010<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/oriamendi.eus\/es\/2026\/02\/07\/ansa-ii-deja-en-ocho-tantos-a-juanenea\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Ansa II deja en ocho tantos a Juanenea | Oriamendi 2010\" \/>\n<meta property=\"og:description\" content=\"Ansa II ha comenzado de la mejor manera la liguilla del Torneo Masters Kutxabank despu\u00e9s de ganar 30-8 a Juanenea, actual campe\u00f3n del individual. Este marcador deja a Juanenea con menos un punto y Ansa suma cuatro puntos. Por lo tanto, el delantero de Urnieta tiene pie y medio en la final del campeonato. El [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/oriamendi.eus\/es\/2026\/02\/07\/ansa-ii-deja-en-ocho-tantos-a-juanenea\/\" \/>\n<meta property=\"og:site_name\" content=\"Oriamendi 2010\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/oriamendi2010remonte\/\" \/>\n<meta property=\"article:published_time\" content=\"2026-02-07T17:37:03+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/oriamendi.eus\/wp-content\/uploads\/2026\/01\/Albistea_Irabazi_AnsaII.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"800\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"I\u00f1igo Go\u00f1i\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@oriamendi2010\" \/>\n<meta name=\"twitter:site\" content=\"@oriamendi2010\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"I\u00f1igo Go\u00f1i\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/oriamendi.eus\/es\/2026\/02\/07\/ansa-ii-deja-en-ocho-tantos-a-juanenea\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/oriamendi.eus\/es\/2026\/02\/07\/ansa-ii-deja-en-ocho-tantos-a-juanenea\/\"},\"author\":{\"name\":\"I\u00f1igo Go\u00f1i\",\"@id\":\"https:\/\/oriamendi.eus\/es\/#\/schema\/person\/c0bd06c6c747674306a5c82563e2339a\"},\"headline\":\"Ansa II deja en ocho tantos a Juanenea\",\"datePublished\":\"2026-02-07T17:37:03+00:00\",\"dateModified\":\"2026-02-07T17:37:03+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/oriamendi.eus\/es\/2026\/02\/07\/ansa-ii-deja-en-ocho-tantos-a-juanenea\/\"},\"wordCount\":220,\"publisher\":{\"@id\":\"https:\/\/oriamendi.eus\/es\/#organization\"},\"articleSection\":[\"Sin categorizar\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/oriamendi.eus\/es\/2026\/02\/07\/ansa-ii-deja-en-ocho-tantos-a-juanenea\/\",\"url\":\"https:\/\/oriamendi.eus\/es\/2026\/02\/07\/ansa-ii-deja-en-ocho-tantos-a-juanenea\/\",\"name\":\"Ansa II deja en ocho tantos a Juanenea | Oriamendi 2010\",\"isPartOf\":{\"@id\":\"https:\/\/oriamendi.eus\/es\/#website\"},\"datePublished\":\"2026-02-07T17:37:03+00:00\",\"dateModified\":\"2026-02-07T17:37:03+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/oriamendi.eus\/es\/2026\/02\/07\/ansa-ii-deja-en-ocho-tantos-a-juanenea\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/oriamendi.eus\/es\/2026\/02\/07\/ansa-ii-deja-en-ocho-tantos-a-juanenea\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/oriamendi.eus\/es\/2026\/02\/07\/ansa-ii-deja-en-ocho-tantos-a-juanenea\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\/\/oriamendi.eus\/es\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Ansa II deja en ocho tantos a Juanenea\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/oriamendi.eus\/es\/#website\",\"url\":\"https:\/\/oriamendi.eus\/es\/\",\"name\":\"Oriamendi\",\"description\":\"Remonte en Galarreta. Hernani. Gipuzkoa\",\"publisher\":{\"@id\":\"https:\/\/oriamendi.eus\/es\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/oriamendi.eus\/es\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/oriamendi.eus\/es\/#organization\",\"name\":\"Oriamendi\",\"url\":\"https:\/\/oriamendi.eus\/es\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/oriamendi.eus\/es\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/oriamendi.eus\/wp-content\/uploads\/2020\/06\/logo-oriamendi.png\",\"contentUrl\":\"https:\/\/oriamendi.eus\/wp-content\/uploads\/2020\/06\/logo-oriamendi.png\",\"width\":300,\"height\":90,\"caption\":\"Oriamendi\"},\"image\":{\"@id\":\"https:\/\/oriamendi.eus\/es\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/oriamendi2010remonte\/\",\"https:\/\/twitter.com\/oriamendi2010\",\"https:\/\/www.instagram.com\/galarretajaialai\/\",\"https:\/\/www.youtube.com\/channel\/UC8gVNzQqB1iwnC-_rI-ihmA\/featured\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/oriamendi.eus\/es\/#\/schema\/person\/c0bd06c6c747674306a5c82563e2339a\",\"name\":\"I\u00f1igo Go\u00f1i\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/oriamendi.eus\/es\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/fbb07ffc7b803bbfcc2b6419c06abd3a?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/fbb07ffc7b803bbfcc2b6419c06abd3a?s=96&d=mm&r=g\",\"caption\":\"I\u00f1igo Go\u00f1i\"},\"url\":\"https:\/\/oriamendi.eus\/es\/author\/om-berriak\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Ansa II deja en ocho tantos a Juanenea | Oriamendi 2010","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/oriamendi.eus\/es\/2026\/02\/07\/ansa-ii-deja-en-ocho-tantos-a-juanenea\/","og_locale":"es_ES","og_type":"article","og_title":"Ansa II deja en ocho tantos a Juanenea | Oriamendi 2010","og_description":"Ansa II ha comenzado de la mejor manera la liguilla del Torneo Masters Kutxabank despu\u00e9s de ganar 30-8 a Juanenea, actual campe\u00f3n del individual. Este marcador deja a Juanenea con menos un punto y Ansa suma cuatro puntos. Por lo tanto, el delantero de Urnieta tiene pie y medio en la final del campeonato. El [&hellip;]","og_url":"https:\/\/oriamendi.eus\/es\/2026\/02\/07\/ansa-ii-deja-en-ocho-tantos-a-juanenea\/","og_site_name":"Oriamendi 2010","article_publisher":"https:\/\/www.facebook.com\/oriamendi2010remonte\/","article_published_time":"2026-02-07T17:37:03+00:00","og_image":[{"width":1200,"height":800,"url":"https:\/\/oriamendi.eus\/wp-content\/uploads\/2026\/01\/Albistea_Irabazi_AnsaII.jpg","type":"image\/jpeg"}],"author":"I\u00f1igo Go\u00f1i","twitter_card":"summary_large_image","twitter_creator":"@oriamendi2010","twitter_site":"@oriamendi2010","twitter_misc":{"Escrito por":"I\u00f1igo Go\u00f1i","Tiempo de lectura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/oriamendi.eus\/es\/2026\/02\/07\/ansa-ii-deja-en-ocho-tantos-a-juanenea\/#article","isPartOf":{"@id":"https:\/\/oriamendi.eus\/es\/2026\/02\/07\/ansa-ii-deja-en-ocho-tantos-a-juanenea\/"},"author":{"name":"I\u00f1igo Go\u00f1i","@id":"https:\/\/oriamendi.eus\/es\/#\/schema\/person\/c0bd06c6c747674306a5c82563e2339a"},"headline":"Ansa II deja en ocho tantos a Juanenea","datePublished":"2026-02-07T17:37:03+00:00","dateModified":"2026-02-07T17:37:03+00:00","mainEntityOfPage":{"@id":"https:\/\/oriamendi.eus\/es\/2026\/02\/07\/ansa-ii-deja-en-ocho-tantos-a-juanenea\/"},"wordCount":220,"publisher":{"@id":"https:\/\/oriamendi.eus\/es\/#organization"},"articleSection":["Sin categorizar"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/oriamendi.eus\/es\/2026\/02\/07\/ansa-ii-deja-en-ocho-tantos-a-juanenea\/","url":"https:\/\/oriamendi.eus\/es\/2026\/02\/07\/ansa-ii-deja-en-ocho-tantos-a-juanenea\/","name":"Ansa II deja en ocho tantos a Juanenea | Oriamendi 2010","isPartOf":{"@id":"https:\/\/oriamendi.eus\/es\/#website"},"datePublished":"2026-02-07T17:37:03+00:00","dateModified":"2026-02-07T17:37:03+00:00","breadcrumb":{"@id":"https:\/\/oriamendi.eus\/es\/2026\/02\/07\/ansa-ii-deja-en-ocho-tantos-a-juanenea\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/oriamendi.eus\/es\/2026\/02\/07\/ansa-ii-deja-en-ocho-tantos-a-juanenea\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/oriamendi.eus\/es\/2026\/02\/07\/ansa-ii-deja-en-ocho-tantos-a-juanenea\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/oriamendi.eus\/es\/"},{"@type":"ListItem","position":2,"name":"Ansa II deja en ocho tantos a Juanenea"}]},{"@type":"WebSite","@id":"https:\/\/oriamendi.eus\/es\/#website","url":"https:\/\/oriamendi.eus\/es\/","name":"Oriamendi","description":"Remonte en Galarreta. Hernani. Gipuzkoa","publisher":{"@id":"https:\/\/oriamendi.eus\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/oriamendi.eus\/es\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/oriamendi.eus\/es\/#organization","name":"Oriamendi","url":"https:\/\/oriamendi.eus\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/oriamendi.eus\/es\/#\/schema\/logo\/image\/","url":"https:\/\/oriamendi.eus\/wp-content\/uploads\/2020\/06\/logo-oriamendi.png","contentUrl":"https:\/\/oriamendi.eus\/wp-content\/uploads\/2020\/06\/logo-oriamendi.png","width":300,"height":90,"caption":"Oriamendi"},"image":{"@id":"https:\/\/oriamendi.eus\/es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/oriamendi2010remonte\/","https:\/\/twitter.com\/oriamendi2010","https:\/\/www.instagram.com\/galarretajaialai\/","https:\/\/www.youtube.com\/channel\/UC8gVNzQqB1iwnC-_rI-ihmA\/featured"]},{"@type":"Person","@id":"https:\/\/oriamendi.eus\/es\/#\/schema\/person\/c0bd06c6c747674306a5c82563e2339a","name":"I\u00f1igo Go\u00f1i","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/oriamendi.eus\/es\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/fbb07ffc7b803bbfcc2b6419c06abd3a?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/fbb07ffc7b803bbfcc2b6419c06abd3a?s=96&d=mm&r=g","caption":"I\u00f1igo Go\u00f1i"},"url":"https:\/\/oriamendi.eus\/es\/author\/om-berriak\/"}]}},"_links":{"self":[{"href":"https:\/\/oriamendi.eus\/es\/wp-json\/wp\/v2\/posts\/9497"}],"collection":[{"href":"https:\/\/oriamendi.eus\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/oriamendi.eus\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/oriamendi.eus\/es\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/oriamendi.eus\/es\/wp-json\/wp\/v2\/comments?post=9497"}],"version-history":[{"count":1,"href":"https:\/\/oriamendi.eus\/es\/wp-json\/wp\/v2\/posts\/9497\/revisions"}],"predecessor-version":[{"id":9498,"href":"https:\/\/oriamendi.eus\/es\/wp-json\/wp\/v2\/posts\/9497\/revisions\/9498"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/oriamendi.eus\/es\/wp-json\/wp\/v2\/media\/9496"}],"wp:attachment":[{"href":"https:\/\/oriamendi.eus\/es\/wp-json\/wp\/v2\/media?parent=9497"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/oriamendi.eus\/es\/wp-json\/wp\/v2\/categories?post=9497"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/oriamendi.eus\/es\/wp-json\/wp\/v2\/tags?post=9497"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}